{"id":8082,"date":"2024-09-30T13:38:22","date_gmt":"2024-09-30T13:38:22","guid":{"rendered":"https:\/\/jerznerhof.at\/hochzeiger-rocks\/"},"modified":"2026-04-01T13:51:05","modified_gmt":"2026-04-01T13:51:05","slug":"hochzeiger-rocks","status":"publish","type":"page","link":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/","title":{"rendered":"Hochzeiger Summer Opening"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8082\" class=\"elementor elementor-8082 elementor-60\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1735cbb7 e-flex e-con-boxed e-con e-parent\" data-id=\"1735cbb7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-15f9e994 e-con-full e-flex e-con e-child\" data-id=\"15f9e994\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e34d8cf elementor-widget elementor-widget-heading\" data-id=\"7e34d8cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Hochzeiger Summer Opening<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32ade73 elementor-widget elementor-widget-heading\" data-id=\"32ade73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Atmospheric kickoff to the 2026 summer season<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fefefad link-beige elementor-widget elementor-widget-text-editor\" data-id=\"4fefefad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"53\" data-end=\"125\"><strong data-start=\"53\" data-end=\"123\">Sunday, June 21, 2026 | Hochzeiger Hiking Area \u2013 Zeiger Restaurant<\/strong><\/p>\n<p><\/p>\n<p data-start=\"127\" data-end=\"382\">Soon, the Hochzeiger will kick off the new hiking season with music! From 11:30 AM, enjoy live music and entertainment with the Oberleinern &amp; Friends at the Zeiger Restaurant at the mid-station, along with grilled specialties and a generous cake buffet.<\/p>\n<p><\/p>\n<p data-start=\"384\" data-end=\"580\">There\u2019s also a special treat for children: the doors of our bakery will open, and from 1:00 PM to 4:00 PM, kids can decorate cookies and take them home\u2014a perfect opportunity for a family outing!<\/p>\n<p><\/p>\n<p data-start=\"582\" data-end=\"829\">Discounted mountain lift tickets will be available on June 21, 2026! The day ticket (valid for all three summer lifts at Hochzeiger) is available at a special price of \u20ac15.00 for adults. Children born in 2011 or later ride for free. ID required.<\/p>\n<p><\/p>\n<p data-start=\"831\" data-end=\"844\"><strong data-start=\"831\" data-end=\"842\">Program<\/strong><\/p>\n<ul data-start=\"846\" data-end=\"1300\">\n<li data-section-id=\"beaa4s\" data-start=\"846\" data-end=\"975\">From 11:30 AM to around 2:30 PM \u2013 Music &amp; entertainment with the Oberleinern &amp; Friends at the Zeiger Restaurant \u2013 Mid-station<\/li>\n<li data-section-id=\"q5ygj1\" data-start=\"976\" data-end=\"1164\">From 1:00 PM to 4:00 PM \u2013 Open Day at the Children\u2019s Bakery in the Zeiger Restaurant:<br data-start=\"1063\" data-end=\"1066\" \/>The in-house cake bakery opens its doors. Little visitors can bake, decorate, and taste cookies.<\/li>\n<li data-section-id=\"xx002q\" data-start=\"1165\" data-end=\"1262\">Grilled specialties and homemade cakes from the in-house cake bakery at the Zeiger Restaurant<\/li>\n<li data-section-id=\"wru0uz\" data-start=\"1263\" data-end=\"1300\">Zirben carts and bike trails open<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c612c51 elementor-widget elementor-widget-image\" data-id=\"6c612c51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/jerznerhof.at\/wp-content\/uploads\/2026\/04\/medium-bergbahnen-hochzeiger-zeigerrestaurant-4-\u00a9-TVB-Pitztal-Severin-Wegener-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-10707\" alt=\"\" srcset=\"https:\/\/jerznerhof.at\/wp-content\/uploads\/2026\/04\/medium-bergbahnen-hochzeiger-zeigerrestaurant-4-\u00a9-TVB-Pitztal-Severin-Wegener-768x512.jpg 768w, https:\/\/jerznerhof.at\/wp-content\/uploads\/2026\/04\/medium-bergbahnen-hochzeiger-zeigerrestaurant-4-\u00a9-TVB-Pitztal-Severin-Wegener-300x200.jpg 300w, https:\/\/jerznerhof.at\/wp-content\/uploads\/2026\/04\/medium-bergbahnen-hochzeiger-zeigerrestaurant-4-\u00a9-TVB-Pitztal-Severin-Wegener-1024x683.jpg 1024w, https:\/\/jerznerhof.at\/wp-content\/uploads\/2026\/04\/medium-bergbahnen-hochzeiger-zeigerrestaurant-4-\u00a9-TVB-Pitztal-Severin-Wegener-1536x1024.jpg 1536w, https:\/\/jerznerhof.at\/wp-content\/uploads\/2026\/04\/medium-bergbahnen-hochzeiger-zeigerrestaurant-4-\u00a9-TVB-Pitztal-Severin-Wegener.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cac547f e-flex e-con-boxed e-con e-child\" data-id=\"6cac547f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hochzeiger Summer Opening Atmospheric kickoff to the 2026 summer season Sunday, June 21, 2026 | Hochzeiger Hiking Area \u2013 Zeiger Restaurant Soon, the Hochzeiger will kick off the new hiking season with music! From 11:30 AM, enjoy live music and entertainment with the Oberleinern &amp; Friends at the Zeiger Restaurant at the mid-station, along with [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8090,"menu_order":25,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8082","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hochzeiger Summer Opening 2026 | Live Music<\/title>\n<meta name=\"description\" content=\"On June 21, 2026, the Hochzeiger hiking area kicks off the new 2026 summer season! A great atmosphere with live music is guaranteed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hochzeiger Summer Opening 2026 | Live Music\" \/>\n<meta property=\"og:description\" content=\"On June 21, 2026, the Hochzeiger hiking area kicks off the new 2026 summer season! A great atmosphere with live music is guaranteed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/\" \/>\n<meta property=\"og:site_name\" content=\"Jerzner Hof****s\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T13:51:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/events\\\/hochzeiger-rocks\\\/\",\"url\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/events\\\/hochzeiger-rocks\\\/\",\"name\":\"Hochzeiger Summer Opening 2026 | Live Music\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/#website\"},\"datePublished\":\"2024-09-30T13:38:22+00:00\",\"dateModified\":\"2026-04-01T13:51:05+00:00\",\"description\":\"On June 21, 2026, the Hochzeiger hiking area kicks off the new 2026 summer season! A great atmosphere with live music is guaranteed!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/events\\\/hochzeiger-rocks\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jerznerhof.at\\\/en\\\/events\\\/hochzeiger-rocks\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/events\\\/hochzeiger-rocks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hochzeiger Summer Opening\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/\",\"name\":\"Jerzner Hof****s\",\"description\":\"Wellnesshotel im Pitztal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/#organization\",\"name\":\"Jerzner Hof****s\",\"url\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jerznerhof.at\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/2024_Logo_Jerzner-Hof_Logo-mit-Sterne-Superior_hell.svg\",\"contentUrl\":\"https:\\\/\\\/jerznerhof.at\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/2024_Logo_Jerzner-Hof_Logo-mit-Sterne-Superior_hell.svg\",\"width\":300,\"height\":225,\"caption\":\"Jerzner Hof****s\"},\"image\":{\"@id\":\"https:\\\/\\\/jerznerhof.at\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hochzeiger Summer Opening 2026 | Live Music","description":"On June 21, 2026, the Hochzeiger hiking area kicks off the new 2026 summer season! A great atmosphere with live music is guaranteed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/","og_locale":"en_US","og_type":"article","og_title":"Hochzeiger Summer Opening 2026 | Live Music","og_description":"On June 21, 2026, the Hochzeiger hiking area kicks off the new 2026 summer season! A great atmosphere with live music is guaranteed!","og_url":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/","og_site_name":"Jerzner Hof****s","article_modified_time":"2026-04-01T13:51:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/","url":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/","name":"Hochzeiger Summer Opening 2026 | Live Music","isPartOf":{"@id":"https:\/\/jerznerhof.at\/en\/#website"},"datePublished":"2024-09-30T13:38:22+00:00","dateModified":"2026-04-01T13:51:05+00:00","description":"On June 21, 2026, the Hochzeiger hiking area kicks off the new 2026 summer season! A great atmosphere with live music is guaranteed!","breadcrumb":{"@id":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jerznerhof.at\/en\/events\/hochzeiger-rocks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/jerznerhof.at\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/jerznerhof.at\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Hochzeiger Summer Opening"}]},{"@type":"WebSite","@id":"https:\/\/jerznerhof.at\/en\/#website","url":"https:\/\/jerznerhof.at\/en\/","name":"Jerzner Hof****s","description":"Wellnesshotel im Pitztal","publisher":{"@id":"https:\/\/jerznerhof.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jerznerhof.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jerznerhof.at\/en\/#organization","name":"Jerzner Hof****s","url":"https:\/\/jerznerhof.at\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jerznerhof.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/jerznerhof.at\/wp-content\/uploads\/2024\/10\/2024_Logo_Jerzner-Hof_Logo-mit-Sterne-Superior_hell.svg","contentUrl":"https:\/\/jerznerhof.at\/wp-content\/uploads\/2024\/10\/2024_Logo_Jerzner-Hof_Logo-mit-Sterne-Superior_hell.svg","width":300,"height":225,"caption":"Jerzner Hof****s"},"image":{"@id":"https:\/\/jerznerhof.at\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/pages\/8082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/comments?post=8082"}],"version-history":[{"count":10,"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/pages\/8082\/revisions"}],"predecessor-version":[{"id":10739,"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/pages\/8082\/revisions\/10739"}],"up":[{"embeddable":true,"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/pages\/8090"}],"wp:attachment":[{"href":"https:\/\/jerznerhof.at\/en\/wp-json\/wp\/v2\/media?parent=8082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}